{"id":9,"count":117,"description":"","link":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/","name":"Dynamics","slug":"dynamics","taxonomy":"category","parent":6,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dynamics Archives - Regents Physics<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dynamics Archives - Regents Physics\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/\" \/>\n<meta property=\"og:site_name\" content=\"Regents Physics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aplusphysics\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/topics\\\/mechanics\\\/dynamics\\\/\",\"url\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/topics\\\/mechanics\\\/dynamics\\\/\",\"name\":\"Dynamics Archives - Regents Physics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/topics\\\/mechanics\\\/dynamics\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/topics\\\/mechanics\\\/dynamics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mechanics\",\"item\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/topics\\\/mechanics\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dynamics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/#website\",\"url\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/\",\"name\":\"Regents Physics\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/#organization\",\"name\":\"APlusPhysics\",\"url\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/APlusPhysics_Logo_HDef.png\",\"contentUrl\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/APlusPhysics_Logo_HDef.png\",\"width\":1500,\"height\":1069,\"caption\":\"APlusPhysics\"},\"image\":{\"@id\":\"https:\\\/\\\/aplusphysics.com\\\/wordpress\\\/regents\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aplusphysics\",\"https:\\\/\\\/x.com\\\/aplusphysics\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/aplusphysics\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/fizziksguy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dynamics Archives - Regents Physics","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/","og_locale":"en_US","og_type":"article","og_title":"Dynamics Archives - Regents Physics","og_url":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/","og_site_name":"Regents Physics","twitter_card":"summary_large_image","twitter_site":"@aplusphysics","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/","url":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/","name":"Dynamics Archives - Regents Physics","isPartOf":{"@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/#website"},"breadcrumb":{"@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/dynamics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aplusphysics.com\/wordpress\/regents\/"},{"@type":"ListItem","position":2,"name":"Mechanics","item":"https:\/\/aplusphysics.com\/wordpress\/regents\/topics\/mechanics\/"},{"@type":"ListItem","position":3,"name":"Dynamics"}]},{"@type":"WebSite","@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/#website","url":"https:\/\/aplusphysics.com\/wordpress\/regents\/","name":"Regents Physics","description":"","publisher":{"@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aplusphysics.com\/wordpress\/regents\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/#organization","name":"APlusPhysics","url":"https:\/\/aplusphysics.com\/wordpress\/regents\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/#\/schema\/logo\/image\/","url":"https:\/\/aplusphysics.com\/wordpress\/regents\/wp-content\/uploads\/2015\/06\/APlusPhysics_Logo_HDef.png","contentUrl":"https:\/\/aplusphysics.com\/wordpress\/regents\/wp-content\/uploads\/2015\/06\/APlusPhysics_Logo_HDef.png","width":1500,"height":1069,"caption":"APlusPhysics"},"image":{"@id":"https:\/\/aplusphysics.com\/wordpress\/regents\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aplusphysics","https:\/\/x.com\/aplusphysics","https:\/\/www.linkedin.com\/in\/aplusphysics\/","https:\/\/www.youtube.com\/user\/fizziksguy"]}]}},"_links":{"self":[{"href":"https:\/\/aplusphysics.com\/wordpress\/regents\/wp-json\/wp\/v2\/categories\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aplusphysics.com\/wordpress\/regents\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/aplusphysics.com\/wordpress\/regents\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/aplusphysics.com\/wordpress\/regents\/wp-json\/wp\/v2\/categories\/6"}],"wp:post_type":[{"href":"https:\/\/aplusphysics.com\/wordpress\/regents\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}